{"id":83090,"date":"2026-04-20T11:47:00","date_gmt":"2026-04-20T09:47:00","guid":{"rendered":"https:\/\/village-flottant-pressac.com\/?page_id=83090"},"modified":"2026-04-21T14:25:44","modified_gmt":"2026-04-21T12:25:44","slug":"bogenschiessen","status":"publish","type":"page","link":"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/bogenschiessen\/","title":{"rendered":"Bogenschie\u00dfen"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_slider show_arrows=&#8220;off&#8220; _builder_version=&#8220;4.17.3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_slide use_bg_overlay=&#8220;off&#8220; use_text_overlay=&#8220;off&#8220; _builder_version=&#8220;4.17.3&#8243; background_color=&#8220;#ffffff&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/tir-a-l-arc-2026.jpg&#8220; background_enable_image=&#8220;on&#8220; button_on_hover=&#8220;on&#8220; custom_padding=&#8220;200px||200px||true&#8220; global_colors_info=&#8220;{}&#8220; sticky_transition=&#8220;on&#8220;][\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;off|off|off&#8220; module_id=&#8220;form_gene&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;rgba(0,0,0,0)&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;1px||1px||true|true&#8220; z_index_tablet=&#8220;500&#8243; custom_css_main_element=&#8220; z-index: 100;||&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; collapsed=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_5,1_5,3_5&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; disabled_on=&#8220;on|on|on&#8220; module_class=&#8220;form_nova&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; custom_margin=&#8220;-85px||||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; disabled=&#8220;on&#8220; collapsed=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|0px||&#8220; custom_css_main_element=&#8220;width:15% !important;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; text_text_color=&#8220;#39a09b&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Je cherche :<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|0px||&#8220; custom_css_main_element=&#8220;width:30%!important;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_code module_id=&#8220;form_general_tous&#8220; module_class=&#8220;code_form_general_novaresa &#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"select-form-general\"><!-- [et_pb_line_break_holder] --><select id=\"select\" class=\"design_select_form_novaresa\"><!-- [et_pb_line_break_holder] --><option id=\"1\" name=\"tous\" value=\"tous\">Tous<\/option><!-- [et_pb_line_break_holder] --><option id=\"2\" name=\"lodges\" value=\"lodges\">Lodges<\/option><!-- [et_pb_line_break_holder] --><option id=\"3\" name=\"cabanes duo\" value=\"cabanes duo\">Cabanes DUO (2-3 pers. max)<\/option><!-- [et_pb_line_break_holder] --><option id=\"4\" name=\"cabanes familiales\" value=\"cabanes familiales\">Cabanes FAMILIALES (4 pers. min)<\/option><!-- [et_pb_line_break_holder] --><option id=\"5\" name=\"tentes safaris\" value=\"tentes safaris\">Tentes Safari<\/option><!-- [et_pb_line_break_holder] -->  <\/select><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; custom_css_main_element=&#8220;width:55%!important;&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_code module_id=&#8220;formtous&#8220; module_class=&#8220;code_form_general_novaresa&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<form id=\"form1\" class=\"form_general_novaresa\" method=\"get\" action=\"https:\/\/village-flottant-pressac.com\/reservation\/\"><!-- [et_pb_line_break_holder] -->  <input placeholder=\"Arriv\u00e9e\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"from\"name=\"date_from\" required=\"Mettre la date d'arriv\u00e9e\"\/><!-- [et_pb_line_break_holder] -->  <input placeholder=\"D\u00e9part\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"to\" name=\"date_to\" required=\"Mettre la date de d\u00e9part\"\/><!-- [et_pb_line_break_holder] -->   <input class=\"button_submit design_form_button_novaresa\" type=\"submit\" value=\"Rechercher\" \/><!-- [et_pb_line_break_holder] --><\/form>\n<p>[\/et_pb_code][et_pb_code module_id=&#8220;formlodge&#8220; module_class=&#8220;code_form_general_novaresa&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<form id=\"form2\" class=\"form_general_novaresa\" method=\"get\" action=\"https:\/\/village-flottant-pressac.com\/reservation-lodges\/\"><!-- [et_pb_line_break_holder] -->  <input placeholder=\"Arriv\u00e9e\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"fromcab\" name=\"date_from\" required=\"Mettre la date d'arriv\u00e9e\"\/><!-- [et_pb_line_break_holder] -->  <input placeholder=\"D\u00e9part\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"tocab\" name=\"date_to\" required=\"Mettre la date de d\u00e9part\"\/><!-- [et_pb_line_break_holder] -->  <input class=\"button_submit design_form_button_novaresa\" type=\"submit\" value=\"Rechercher\" \/><!-- [et_pb_line_break_holder] --><\/form>\n<p>[\/et_pb_code][et_pb_code module_id=&#8220;formcab&#8220; module_class=&#8220;code_form_general_novaresa&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<form id=\"form3\" class=\"form_general_novaresa\" method=\"get\" action=\"https:\/\/village-flottant-pressac.com\/reservation-cabanes-duo\/\"><!-- [et_pb_line_break_holder] -->  <input placeholder=\"Arriv\u00e9e\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"fromlodge\" name=\"date_from\" required=\"Mettre la date d'arriv\u00e9e\"\/><!-- [et_pb_line_break_holder] -->  <input placeholder=\"D\u00e9part\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"tocabane\" name=\"date_to\" required=\"Mettre la date de d\u00e9part\"\/><!-- [et_pb_line_break_holder] -->  <input class=\"button_submit design_form_button_novaresa\" type=\"submit\" value=\"Rechercher\" \/><!-- [et_pb_line_break_holder] --><\/form>\n<p>[\/et_pb_code][et_pb_code module_id=&#8220;formfam&#8220; module_class=&#8220;code_form_general_novaresa&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<form id=\"form4\" class=\"form_general_novaresa\" method=\"get\" action=\"https:\/\/village-flottant-pressac.com\/reservation-cabanes-familiales\/\"><!-- [et_pb_line_break_holder] -->  <input placeholder=\"Arriv\u00e9e\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"fromfamiliales\" name=\"date_from\" required=\"Mettre la date d'arriv\u00e9e\"\/><!-- [et_pb_line_break_holder] -->  <input placeholder=\"D\u00e9part\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"tofamiliales\" name=\"date_to\" required=\"Mettre la date de d\u00e9part\"\/><!-- [et_pb_line_break_holder] -->  <input class=\"button_submit design_form_button_novaresa\" type=\"submit\" value=\"Rechercher\" \/><!-- [et_pb_line_break_holder] --><\/form>\n<p>[\/et_pb_code][et_pb_code disabled_on=&#8220;off|off|off&#8220; module_id=&#8220;formtente&#8220; module_class=&#8220;code_form_general_novaresa&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<form id=\"form5\" class=\"form_general_novaresa\" method=\"get\" action=\"https:\/\/village-flottant-pressac.com\/reservation-tentes\"><!-- [et_pb_line_break_holder] -->  <input placeholder=\"Arriv\u00e9e\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"fromtente\" name=\"date_from\" required=\"Mettre la date d'arriv\u00e9e\"\/><!-- [et_pb_line_break_holder] -->  <input placeholder=\"D\u00e9part\" type=\"text\" class=\"design_form_novaresa picto_reservation date\" id=\"totente\" name=\"date_to\" required=\"Mettre la date de d\u00e9part\"\/><!-- [et_pb_line_break_holder] -->  <input class=\"button_submit design_form_button_novaresa\" type=\"submit\" value=\"Rechercher\" \/><!-- [et_pb_line_break_holder] --><\/form>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;1&#8243; disabled_on=&#8220;off|off|off&#8220; module_class=&#8220;form_nova&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;-45px||||false|false&#8220; custom_padding=&#8220;20px|20px|20px|20px|true|true&#8220; sticky_position=&#8220;bottom&#8220; sticky_limit_top=&#8220;body&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|0px||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_button button_url=&#8220;https:\/\/www.sandaya.fr\/nos-campings\/village-flottant-de-pressac\/nos-locations#menu&#8220; button_text=&#8220;Buchen Sie Ihren Aufenthalt im Village Flottant von Pressac&#8220; button_alignment=&#8220;center&#8220; disabled_on=&#8220;off|off|off&#8220; admin_label=&#8220;Bouton RESERVATION&#8220; _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][et_pb_button button_url=&#8220;tel:0586160225&#8243; button_text=&#8220;R\u00e9server par t\u00e9l\u00e9phone au 05 86 16 02 25&#8243; button_alignment=&#8220;center&#8220; disabled_on=&#8220;on|on|on&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;30px|0px|30px|0px|true|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0|0px|0|0px|false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; header_font=&#8220;||||||||&#8220; header_2_font=&#8220;||||||||&#8220; header_2_text_align=&#8220;left&#8220; header_2_text_color=&#8220;#1e6262&#8243; header_2_font_size=&#8220;28px&#8220; header_2_letter_spacing=&#8220;2px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 class=\"p1\"><strong>Bogenschie\u00dfen<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;3_5,2_5&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.17.3&#8243; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#1e6263&#8243; header_font=&#8220;||||||||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p data-start=\"423\" data-end=\"585\">Kostenlose Aktivit\u00e4t, die im Juli und August 2026 zweimal pro Woche f\u00fcr Erwachsene und Kinder angeboten wird.<\/p>\n<p data-start=\"423\" data-end=\"585\"><strong>Informationen und Anmeldung bei La Capitainerie.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/tir-a-l-arc-2026-banner.jpg&#8220; title_text=&#8220;tir-a-l-arc-2026-banner&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.17.3&#8243; global_colors_info=&#8220;{}&#8220;]<br \/>\n[\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.17.3&#8243; background_color=&#8220;#f7f7f7&#8243; custom_padding=&#8220;0|0px|0|0px|false|false&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; global_module=&#8220;83317&#8243; theme_builder_area=&#8220;post_content&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;TITRE &#8211; Les activit\u00e9s&#8220; _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_2_font=&#8220;|||on|||||&#8220; header_2_text_align=&#8220;center&#8220; header_2_text_color=&#8220;#1e6262&#8243; header_2_font_size=&#8220;28px&#8220; header_2_letter_spacing=&#8220;2px&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h2 class=\"p1\"><span>Aktivit\u00e4ten<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8220;4.17.3&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<!-- The Grid Plugin Version 2.8.1 --><!-- The Grid Cache Enabled - Date: 05\/06\/26, 10:37:14 PM --><!-- The Grid Wrapper Start --><div class=\"tg-grid-wrapper tg-txt full-height\" id=\"grid-83313\" data-version=\"2.8.1\"><!-- The Grid Fonts --><link href=\"\/\/fonts.googleapis.com\/css?family=News+Cycle%3A400%26subset%3Dlatin-ext\" rel=\"stylesheet\" property=\"stylesheet\" type=\"text\/css\" media=\"all\"><!-- The Grid Styles --><style class=\"tg-grid-styles\" type=\"text\/css\">#grid-83313 .tg-nav-color:not(.dots):not(.tg-dropdown-value):not(.tg-dropdown-title):hover,#grid-83313 .tg-nav-color:hover .tg-nav-color,#grid-83313 .tg-page-number.tg-page-current,#grid-83313 .tg-filter.tg-filter-active span{color:#ff6863}#grid-83313 .tg-filter:before,#grid-83313 .tg-filter.tg-filter-active:before{color:#999999}#grid-83313 .tg-dropdown-holder,#grid-83313 .tg-search-inner,#grid-83313 .tg-sorter-order{border:1px solid #DDDDDD}#grid-83313 .tg-search-clear,#grid-83313 .tg-search-clear:hover{border:none;border-left:1px solid #DDDDDD}.tg-txt .tg-nav-font,.tg-txt input[type=text].tg-search{font-size:14px;font-weight:600}.tg-txt .tg-search::-webkit-input-placeholder{font-size:14px}.tg-txt .tg-search::-moz-placeholder{font-size:14px}.tg-txt .tg-search:-ms-input-placeholder{font-size:14px}.tg-txt .tg-icon-left-arrow:before{content:\"\\e604\";font-size:32px;font-weight:100}.tg-txt .tg-icon-right-arrow:before{content:\"\\e602\";font-size:32px;font-weight:100}.tg-txt .tg-icon-dropdown-open:before,.tg-txt .tg-icon-sorter-down:before{content:\"\\e60a\"}.tg-txt .tg-icon-sorter-up:before{content:\"\\e609\"}.tg-txt .tg-search-clear:before{content:\"\\e611\";font-weight:300}.tg-txt .tg-search-icon:before{content:\"\\e62e\";font-size:16px;font-weight:600}#grid-83313 .tg-nav-color,#grid-83313 .tg-search-icon:hover:before,#grid-83313 .tg-search-icon:hover input,#grid-83313 .tg-disabled:hover .tg-icon-left-arrow,#grid-83313 .tg-disabled:hover .tg-icon-right-arrow,#grid-83313 .tg-dropdown-title.tg-nav-color:hover{color:#999999}#grid-83313 input.tg-search:hover{color:#999999 !important}#grid-83313 input.tg-search::-webkit-input-placeholder{color:#999999}#grid-83313 input.tg-search::-moz-placeholder{color:#999999;opacity:1}#grid-83313 input.tg-search:-ms-input-placeholder{color:#999999}.grid-83313 .tg-dropdown-item{color:#777777;background:#ffffff}.grid-83313 .tg-filter-active,.grid-83313 .tg-dropdown-item:hover{color:#444444;background:#f5f6fa}#grid-83313 .tg-slider-bullets li.tg-active-item span{background:#59585b}#grid-83313 .tg-slider-bullets li span{background:#DDDDDD}.tg-activities-de a:not([class*=\"tg-element-\"]),.tg-activities-de a:not([class*=\"tg-element-\"]):active,.tg-activities-de a:not([class*=\"tg-element-\"]):focus,.tg-activities-de [class*=\"tg-element-\"] *:not(del){margin:0;padding:0;color:inherit !important;text-align:inherit;font-size:inherit;font-style:inherit;line-height:inherit;font-weight:inherit;text-transform:inherit;text-decoration:inherit;-webkit-box-shadow:none;box-shadow:none;border:none}.tg-activities-de [class*=\"tg-element-\"],.tg-activities-de .tg-item-overlay,.tg-activities-de .tg-center-holder,.tg-activities-de .tg-center-inner > *{vertical-align:middle}.tg-activities-de .tg-item-overlay{position:absolute;display:block;top:0;left:0;bottom:0;right:0;-webkit-transition:all 700ms ease;-moz-transition:all 700ms ease;-ms-transition:all 700ms ease;transition:all 700ms ease}.tg-activities-de .tg-item-media-holder:hover .tg-item-overlay{background-color:rgba(57,160,155,0.36)}.tg-activities-de div.tg-item-media-content{-webkit-transition:all 700ms ease;-moz-transition:all 700ms ease;-ms-transition:all 700ms ease;transition:all 700ms ease}.tg-activities-de div.tg-item-media-content:hover{background-color:rgba(57,160,155,0.38)}.tg-activities-de .tg-element-1{position:relative;font-size:16px;line-height:20px;color:#ffffff;font-weight:400;font-family:News Cycle;text-transform:uppercase;text-align:center;letter-spacing:2px;background-color:#1e6263;display:block;width:100%;min-width:100%;margin:0;padding:16px 0}.tg-activities-de .tg-element-2{position:relative;clear:both;font-size:18px;line-height:22px;font-family:News Cycle;text-align:center;letter-spacing:1px;background-color:#39a09b;display:block;height:100%;min-height:100%;padding:12px;margin:auto;width:fit-content;max-width:80%;opacity:0;visibility:hidden;-webkit-transition:all 340ms ease;-moz-transition:all 340ms ease;-ms-transition:all 340ms ease;transition:all 340ms ease}.tg-activities-de:hover .tg-element-2{opacity:1;visibility:visible}.tg-activities-de .tg-element-2:hover{visibility:visible;opacity:1 !important}.tg-activites-2-peche{height:100px}.tg-item .tg-dark div,.tg-item .tg-dark h1,.tg-item .tg-dark h1 a,.tg-item .tg-dark h2,.tg-item .tg-dark h2 a,.tg-item .tg-dark h3,.tg-item .tg-dark h3 a,.tg-item .tg-dark h4,.tg-item .tg-dark h4 a,.tg-item .tg-dark h5,.tg-item .tg-dark h5 a,.tg-item .tg-dark h6,.tg-item .tg-dark h6 a,.tg-item .tg-dark a,.tg-item .tg-dark a.tg-link-url,.tg-item .tg-dark i,.tg-item .tg-dark .tg-media-button,.tg-item .tg-dark .tg-item-price span{color:#444444;fill:#444444;stroke:#444444;border-color:#444444}.tg-item .tg-dark p,.tg-item .tg-dark ol,.tg-item .tg-dark ul,.tg-item .tg-dark li{color:#777777;fill:#777777;stroke:#777777;border-color:#777777}.tg-item .tg-dark span,.tg-item .tg-dark .no-liked .to-heart-icon path,.tg-item .tg-dark .empty-heart .to-heart-icon path,.tg-item .tg-dark .tg-item-comment i,.tg-item .tg-dark .tg-item-price del span{color:#999999;fill:#999999;stroke:#999999;border-color:#999999}.tg-item .tg-light div,.tg-item .tg-light h1,.tg-item .tg-light h1 a,.tg-item .tg-light h2,.tg-item .tg-light h2 a,.tg-item .tg-light h3,.tg-item .tg-light h3 a,.tg-item .tg-light h4,.tg-item .tg-light h4 a,.tg-item .tg-light h5,.tg-item .tg-light h5 a,.tg-item .tg-light h6,.tg-item .tg-light h6 a,.tg-item .tg-light a,.tg-item .tg-light a.tg-link-url,.tg-item .tg-light i,.tg-item .tg-light .tg-media-button,.tg-item .tg-light .tg-item-price span{color:#ffffff;fill:#ffffff;stroke:#ffffff;border-color:#ffffff}.tg-item .tg-light p,.tg-item .tg-light ol,.tg-item .tg-light ul,.tg-item .tg-light li{color:#f6f6f6;fill:#f6f6f6;stroke:#f6f6f6;border-color:#f6f6f6}.tg-item .tg-light span,.tg-item .tg-light .no-liked .to-heart-icon path,.tg-item .tg-light .empty-heart .to-heart-icon path,.tg-item .tg-light .tg-item-comment i,.tg-item .tg-light .tg-item-price del span{color:#f5f5f5;fill:#f5f5f5;stroke:#f5f5f5;border-color:#f5f5f5}#grid-83313 .tg-item-content-holder{background-color:#ffffff}#grid-83313 .tg-item-overlay{background-color:rgba(22,22,22,0.01)}<\/style><!-- The Grid Item Sizer --><div class=\"tg-grid-sizer\"><\/div><!-- The Grid Gutter Sizer --><div class=\"tg-gutter-sizer\"><\/div><!-- The Grid Items Holder --><div class=\"tg-grid-holder tg-layout-grid\"  data-name=\"Activities DE\"  data-style=\"grid\" data-row=\"1\" data-layout=\"vertical\" data-rtl=\"\" data-fitrows=\"\" data-filtercomb=\"\" data-filterlogic=\"AND\" data-filterload =\"\" data-sortbyload =\"\" data-orderload =\"false\" data-fullwidth=\"\" data-fullheight=\"null\" data-gutters=\"[[320,20],[480,20],[768,20],[980,20],[1200,20],[9999,20]]\" data-slider='{\"itemNav\":\"null\",\"swingSpeed\":0.1,\"cycleBy\":\"null\",\"cycle\":5000,\"startAt\":1}' data-ratio=\"0.67\" data-cols=\"[[320,1],[480,1],[768,2],[980,3],[1200,4],[9999,4]]\" data-rows=\"[[320,200],[480,200],[768,220],[980,220],[1200,240],[9999,240]]\" data-animation='{&quot;name&quot;:&quot;Fade in&quot;,&quot;visible&quot;:&quot;&quot;,&quot;hidden&quot;:&quot;&quot;}' data-transition=\"700ms\" data-ajaxmethod=\"load_more\" data-ajaxdelay=\"100\" data-preloader=\"\" data-itemdelay=\"100\" data-gallery=\"\" data-ajax=\"\"><!-- The Grid item #1 --><article class=\"tg-item tg-post-80359 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2025\/05\/FLO_Drone_006FLO_Drone_006.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Die Lagune<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/die-lagune\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #2 --><article class=\"tg-item tg-post-83205 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/trotinette-2026-banner.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Elektroroller<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/elektroroller\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #3 --><article class=\"tg-item tg-post-83090 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/tir-a-l-arc-2026-banner.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Bogenschie\u00dfen<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/bogenschiessen\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #4 --><article class=\"tg-item tg-post-69814 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/01\/VFP_ACTIVITES_0039_le_futuroscope_30_ans_de_design_thinking_inspire_par_les_nouvelles_technologies.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Tourismus<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/tourismus\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #5 --><article class=\"tg-item tg-post-72092 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_activites_famille_017-1.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Angeln<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/angeln\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #6 --><article class=\"tg-item tg-post-72111 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/GettyImages-949446550.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Wandern<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/wandern\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #7 --><article class=\"tg-item tg-post-72101 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/activite-piscine.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Schwimmbad<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/schwimmbad\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #8 --><article class=\"tg-item tg-post-72078 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_bain_nordique_003-1.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Nordisches Bad<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/nordisches-bad\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><\/div><\/div><!-- The Grid Wrapper End -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_5,1_5,1_5,1_5,1_5&#8243; disabled_on=&#8220;on|on|on&#8220; module_class=&#8220;pack_responsive&#8220; _builder_version=&#8220;4.17.3&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; disabled=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;TITRE &#8211; p\u00eache&#8220; _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;18px&#8220; background_color=&#8220;#1e6263&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;20px||10px|&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h3 class=\"p1\"><span class=\"s1\">angeln<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_cta button_url=&#8220;\/de\/aktivitaeten\/angeln&#8220; button_text=&#8220;Mehr erfahren&#8220; module_class=&#8220;peche&#8220; _builder_version=&#8220;4.16&#8243; body_font=&#8220;||||||||&#8220; background_color=&#8220;rgba(126,190,197,0)&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_activites_famille_016-1.jpg&#8220; background_blend=&#8220;overlay&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#39a09b&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;#39a09b&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;News Cycle||||||||&#8220; button_use_icon=&#8220;off&#8220; button_alignment=&#8220;center&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;100px|5px|100px|5px|true|true&#8220; global_colors_info=&#8220;{}&#8220; filter_hue_rotate__hover=&#8220;0deg&#8220; background__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover=&#8220;#39a09b&#8220; background_color__hover=&#8220;rgba(30,98,99,0.56)&#8220; custom_css_promo_button__hover_enabled=&#8220;on&#8220; custom_padding__hover_enabled=&#8220;on&#8220; custom_padding__hover=&#8220;100px|5px|100px|5px&#8220; button_text_size__hover=&#8220;18px&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;TITRE &#8211; PISCINE&#8220; _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;18px&#8220; background_color=&#8220;#1e6263&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;20px||10px|&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h3 class=\"p1\">schwimmbad<\/h3>\n<p>[\/et_pb_text][et_pb_cta button_url=&#8220;\/de\/aktivitaeten\/schwimmbad&#8220; button_text=&#8220;Mehr erfahren&#8220; module_class=&#8220;peche&#8220; _builder_version=&#8220;4.16&#8243; body_font=&#8220;||||||||&#8220; background_color=&#8220;rgba(126,190,197,0)&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/DSC_0040.jpg&#8220; background_position=&#8220;center_left&#8220; background_blend=&#8220;overlay&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#39a09b&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;#39a09b&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;News Cycle||||||||&#8220; button_use_icon=&#8220;off&#8220; button_alignment=&#8220;center&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;100px|5px|100px|5px|true|true&#8220; global_colors_info=&#8220;{}&#8220; filter_hue_rotate__hover=&#8220;0deg&#8220; background__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover=&#8220;#39a09b&#8220; background_color__hover=&#8220;rgba(30,98,99,0.56)&#8220; custom_css_promo_button__hover_enabled=&#8220;on&#8220; custom_padding__hover_enabled=&#8220;on&#8220; custom_padding__hover=&#8220;100px|5px|100px|5px&#8220; button_text_size__hover=&#8220;18px&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;TITRE &#8211; Randonn\u00e9e&#8220; _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;18px&#8220; background_color=&#8220;#1e6263&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;20px||10px|&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h3 class=\"p1\">wandern<\/h3>\n<p>[\/et_pb_text][et_pb_cta button_url=&#8220;\/de\/aktivitaeten\/wandern&#8220; button_text=&#8220;Mehr erfahren&#8220; module_class=&#8220;peche&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;rgba(126,190,197,0)&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/GettyImages-949446550.jpg&#8220; background_blend=&#8220;overlay&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#39a09b&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;#39a09b&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;News Cycle||||||||&#8220; button_use_icon=&#8220;off&#8220; button_alignment=&#8220;center&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;100px|5px|100px|5px|true|true&#8220; global_colors_info=&#8220;{}&#8220; filter_hue_rotate__hover=&#8220;0deg&#8220; background__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover=&#8220;#39a09b&#8220; background_color__hover=&#8220;rgba(30,98,99,0.56)&#8220; custom_css_promo_button__hover_enabled=&#8220;on&#8220; custom_padding__hover_enabled=&#8220;on&#8220; custom_padding__hover=&#8220;100px|5px|100px|5px&#8220; button_text_size__hover=&#8220;18px&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;18px&#8220; background_color=&#8220;#1e6263&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;20px||10px|&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h3 class=\"p1\">nordisches bad<\/h3>\n<p>[\/et_pb_text][et_pb_cta button_url=&#8220;\/de\/aktivitaeten\/nordisches-bad&#8220; button_text=&#8220;Mehr erfahren&#8220; module_class=&#8220;peche&#8220; _builder_version=&#8220;4.16&#8243; background_color=&#8220;rgba(126,190,197,0)&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_bain_nordique_003-1.jpg&#8220; background_blend=&#8220;overlay&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#39a09b&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;#39a09b&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;News Cycle||||||||&#8220; button_use_icon=&#8220;off&#8220; button_alignment=&#8220;center&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;100px|5px|100px|5px|true|true&#8220; z_index_tablet=&#8220;500&#8243; global_colors_info=&#8220;{}&#8220; filter_hue_rotate__hover=&#8220;0deg&#8220; background__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover=&#8220;#39a09b&#8220; background_color__hover=&#8220;rgba(30,98,99,0.56)&#8220; custom_css_promo_button__hover_enabled=&#8220;on&#8220; custom_padding__hover_enabled=&#8220;on&#8220; custom_padding__hover=&#8220;100px|5px|100px|5px&#8220; button_text_size__hover=&#8220;18px&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8220;1_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220; theme_builder_area=&#8220;post_content&#8220;][et_pb_text admin_label=&#8220;TITRE &#8211; Tourisme&#8220; _builder_version=&#8220;4.16&#8243; header_font=&#8220;||||||||&#8220; header_3_font=&#8220;|||on|||||&#8220; header_3_text_align=&#8220;center&#8220; header_3_text_color=&#8220;#ffffff&#8220; header_3_font_size=&#8220;18px&#8220; background_color=&#8220;#1e6263&#8243; custom_margin=&#8220;||0px|&#8220; custom_padding=&#8220;20px||10px|&#8220; global_colors_info=&#8220;{}&#8220; theme_builder_area=&#8220;post_content&#8220;]<\/p>\n<h3 class=\"p1\">Tourismus<\/h3>\n<p>[\/et_pb_text][et_pb_cta button_url=&#8220;\/de\/aktivitaeten\/tourismus&#8220; button_text=&#8220;Mehr erfahren&#8220; module_class=&#8220;peche &#8220; _builder_version=&#8220;4.16&#8243; body_font=&#8220;||||||||&#8220; background_color=&#8220;rgba(126,190,197,0)&#8220; background_image=&#8220;https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/img3-1.jpg&#8220; background_blend=&#8220;overlay&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#39a09b&#8220; button_border_width=&#8220;0px&#8220; button_border_color=&#8220;#39a09b&#8220; button_border_radius=&#8220;0px&#8220; button_letter_spacing=&#8220;1px&#8220; button_font=&#8220;News Cycle||||||||&#8220; button_use_icon=&#8220;off&#8220; button_alignment=&#8220;center&#8220; custom_margin=&#8220;||&#8220; custom_padding=&#8220;100px|5px|100px|5px|true|true&#8220; global_colors_info=&#8220;{}&#8220; filter_hue_rotate__hover=&#8220;0deg&#8220; background__hover_enabled=&#8220;on&#8220; button_text_color__hover=&#8220;#ffffff&#8220; button_bg_color__hover=&#8220;#39a09b&#8220; background_color__hover=&#8220;rgba(30,98,99,0.56)&#8220; custom_css_promo_button__hover_enabled=&#8220;on&#8220; custom_padding__hover_enabled=&#8220;on&#8220; custom_padding__hover=&#8220;100px|5px|100px|5px&#8220; button_text_size__hover=&#8220;18px&#8220; button_text_color__hover_enabled=&#8220;on&#8220; button_bg_color__hover_enabled=&#8220;on&#8220; theme_builder_area=&#8220;post_content&#8220;][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je cherche :Bogenschie\u00dfenKostenlose Aktivit\u00e4t, die im Juli und August 2026 zweimal pro Woche f\u00fcr Erwachsene und Kinder angeboten wird. Informationen und Anmeldung bei La Capitainerie. Aktivit\u00e4ten<!-- The Grid Plugin Version 2.8.1 --><!-- The Grid Cache Enabled - Date: 05\/06\/26, 10:37:14 PM --><!-- The Grid Wrapper Start --><div class=\"tg-grid-wrapper tg-txt full-height\" id=\"grid-83313\" data-version=\"2.8.1\"><!-- The Grid Fonts --><link href=\"\/\/fonts.googleapis.com\/css?family=News+Cycle%3A400%26subset%3Dlatin-ext\" rel=\"stylesheet\" property=\"stylesheet\" type=\"text\/css\" media=\"all\"><!-- The Grid Styles --><style class=\"tg-grid-styles\" type=\"text\/css\">#grid-83313 .tg-nav-color:not(.dots):not(.tg-dropdown-value):not(.tg-dropdown-title):hover,#grid-83313 .tg-nav-color:hover .tg-nav-color,#grid-83313 .tg-page-number.tg-page-current,#grid-83313 .tg-filter.tg-filter-active span{color:#ff6863}#grid-83313 .tg-filter:before,#grid-83313 .tg-filter.tg-filter-active:before{color:#999999}#grid-83313 .tg-dropdown-holder,#grid-83313 .tg-search-inner,#grid-83313 .tg-sorter-order{border:1px solid #DDDDDD}#grid-83313 .tg-search-clear,#grid-83313 .tg-search-clear:hover{border:none;border-left:1px solid #DDDDDD}.tg-txt .tg-nav-font,.tg-txt input[type=text].tg-search{font-size:14px;font-weight:600}.tg-txt .tg-search::-webkit-input-placeholder{font-size:14px}.tg-txt .tg-search::-moz-placeholder{font-size:14px}.tg-txt .tg-search:-ms-input-placeholder{font-size:14px}.tg-txt .tg-icon-left-arrow:before{content:\"\\e604\";font-size:32px;font-weight:100}.tg-txt .tg-icon-right-arrow:before{content:\"\\e602\";font-size:32px;font-weight:100}.tg-txt .tg-icon-dropdown-open:before,.tg-txt .tg-icon-sorter-down:before{content:\"\\e60a\"}.tg-txt .tg-icon-sorter-up:before{content:\"\\e609\"}.tg-txt .tg-search-clear:before{content:\"\\e611\";font-weight:300}.tg-txt .tg-search-icon:before{content:\"\\e62e\";font-size:16px;font-weight:600}#grid-83313 .tg-nav-color,#grid-83313 .tg-search-icon:hover:before,#grid-83313 .tg-search-icon:hover input,#grid-83313 .tg-disabled:hover .tg-icon-left-arrow,#grid-83313 .tg-disabled:hover .tg-icon-right-arrow,#grid-83313 .tg-dropdown-title.tg-nav-color:hover{color:#999999}#grid-83313 input.tg-search:hover{color:#999999 !important}#grid-83313 input.tg-search::-webkit-input-placeholder{color:#999999}#grid-83313 input.tg-search::-moz-placeholder{color:#999999;opacity:1}#grid-83313 input.tg-search:-ms-input-placeholder{color:#999999}.grid-83313 .tg-dropdown-item{color:#777777;background:#ffffff}.grid-83313 .tg-filter-active,.grid-83313 .tg-dropdown-item:hover{color:#444444;background:#f5f6fa}#grid-83313 .tg-slider-bullets li.tg-active-item span{background:#59585b}#grid-83313 .tg-slider-bullets li span{background:#DDDDDD}.tg-activities-de a:not([class*=\"tg-element-\"]),.tg-activities-de a:not([class*=\"tg-element-\"]):active,.tg-activities-de a:not([class*=\"tg-element-\"]):focus,.tg-activities-de [class*=\"tg-element-\"] *:not(del){margin:0;padding:0;color:inherit !important;text-align:inherit;font-size:inherit;font-style:inherit;line-height:inherit;font-weight:inherit;text-transform:inherit;text-decoration:inherit;-webkit-box-shadow:none;box-shadow:none;border:none}.tg-activities-de [class*=\"tg-element-\"],.tg-activities-de .tg-item-overlay,.tg-activities-de .tg-center-holder,.tg-activities-de .tg-center-inner > *{vertical-align:middle}.tg-activities-de .tg-item-overlay{position:absolute;display:block;top:0;left:0;bottom:0;right:0;-webkit-transition:all 700ms ease;-moz-transition:all 700ms ease;-ms-transition:all 700ms ease;transition:all 700ms ease}.tg-activities-de .tg-item-media-holder:hover .tg-item-overlay{background-color:rgba(57,160,155,0.36)}.tg-activities-de div.tg-item-media-content{-webkit-transition:all 700ms ease;-moz-transition:all 700ms ease;-ms-transition:all 700ms ease;transition:all 700ms ease}.tg-activities-de div.tg-item-media-content:hover{background-color:rgba(57,160,155,0.38)}.tg-activities-de .tg-element-1{position:relative;font-size:16px;line-height:20px;color:#ffffff;font-weight:400;font-family:News Cycle;text-transform:uppercase;text-align:center;letter-spacing:2px;background-color:#1e6263;display:block;width:100%;min-width:100%;margin:0;padding:16px 0}.tg-activities-de .tg-element-2{position:relative;clear:both;font-size:18px;line-height:22px;font-family:News Cycle;text-align:center;letter-spacing:1px;background-color:#39a09b;display:block;height:100%;min-height:100%;padding:12px;margin:auto;width:fit-content;max-width:80%;opacity:0;visibility:hidden;-webkit-transition:all 340ms ease;-moz-transition:all 340ms ease;-ms-transition:all 340ms ease;transition:all 340ms ease}.tg-activities-de:hover .tg-element-2{opacity:1;visibility:visible}.tg-activities-de .tg-element-2:hover{visibility:visible;opacity:1 !important}.tg-activites-2-peche{height:100px}.tg-item .tg-dark div,.tg-item .tg-dark h1,.tg-item .tg-dark h1 a,.tg-item .tg-dark h2,.tg-item .tg-dark h2 a,.tg-item .tg-dark h3,.tg-item .tg-dark h3 a,.tg-item .tg-dark h4,.tg-item .tg-dark h4 a,.tg-item .tg-dark h5,.tg-item .tg-dark h5 a,.tg-item .tg-dark h6,.tg-item .tg-dark h6 a,.tg-item .tg-dark a,.tg-item .tg-dark a.tg-link-url,.tg-item .tg-dark i,.tg-item .tg-dark .tg-media-button,.tg-item .tg-dark .tg-item-price span{color:#444444;fill:#444444;stroke:#444444;border-color:#444444}.tg-item .tg-dark p,.tg-item .tg-dark ol,.tg-item .tg-dark ul,.tg-item .tg-dark li{color:#777777;fill:#777777;stroke:#777777;border-color:#777777}.tg-item .tg-dark span,.tg-item .tg-dark .no-liked .to-heart-icon path,.tg-item .tg-dark .empty-heart .to-heart-icon path,.tg-item .tg-dark .tg-item-comment i,.tg-item .tg-dark .tg-item-price del span{color:#999999;fill:#999999;stroke:#999999;border-color:#999999}.tg-item .tg-light div,.tg-item .tg-light h1,.tg-item .tg-light h1 a,.tg-item .tg-light h2,.tg-item .tg-light h2 a,.tg-item .tg-light h3,.tg-item .tg-light h3 a,.tg-item .tg-light h4,.tg-item .tg-light h4 a,.tg-item .tg-light h5,.tg-item .tg-light h5 a,.tg-item .tg-light h6,.tg-item .tg-light h6 a,.tg-item .tg-light a,.tg-item .tg-light a.tg-link-url,.tg-item .tg-light i,.tg-item .tg-light .tg-media-button,.tg-item .tg-light .tg-item-price span{color:#ffffff;fill:#ffffff;stroke:#ffffff;border-color:#ffffff}.tg-item .tg-light p,.tg-item .tg-light ol,.tg-item .tg-light ul,.tg-item .tg-light li{color:#f6f6f6;fill:#f6f6f6;stroke:#f6f6f6;border-color:#f6f6f6}.tg-item .tg-light span,.tg-item .tg-light .no-liked .to-heart-icon path,.tg-item .tg-light .empty-heart .to-heart-icon path,.tg-item .tg-light .tg-item-comment i,.tg-item .tg-light .tg-item-price del span{color:#f5f5f5;fill:#f5f5f5;stroke:#f5f5f5;border-color:#f5f5f5}#grid-83313 .tg-item-content-holder{background-color:#ffffff}#grid-83313 .tg-item-overlay{background-color:rgba(22,22,22,0.01)}<\/style><!-- The Grid Item Sizer --><div class=\"tg-grid-sizer\"><\/div><!-- The Grid Gutter Sizer --><div class=\"tg-gutter-sizer\"><\/div><!-- The Grid Items Holder --><div class=\"tg-grid-holder tg-layout-grid\"  data-name=\"Activities DE\"  data-style=\"grid\" data-row=\"1\" data-layout=\"vertical\" data-rtl=\"\" data-fitrows=\"\" data-filtercomb=\"\" data-filterlogic=\"AND\" data-filterload =\"\" data-sortbyload =\"\" data-orderload =\"false\" data-fullwidth=\"\" data-fullheight=\"null\" data-gutters=\"[[320,20],[480,20],[768,20],[980,20],[1200,20],[9999,20]]\" data-slider='{\"itemNav\":\"null\",\"swingSpeed\":0.1,\"cycleBy\":\"null\",\"cycle\":5000,\"startAt\":1}' data-ratio=\"0.67\" data-cols=\"[[320,1],[480,1],[768,2],[980,3],[1200,4],[9999,4]]\" data-rows=\"[[320,200],[480,200],[768,220],[980,220],[1200,240],[9999,240]]\" data-animation='{&quot;name&quot;:&quot;Fade in&quot;,&quot;visible&quot;:&quot;&quot;,&quot;hidden&quot;:&quot;&quot;}' data-transition=\"700ms\" data-ajaxmethod=\"load_more\" data-ajaxdelay=\"100\" data-preloader=\"\" data-itemdelay=\"100\" data-gallery=\"\" data-ajax=\"\"><!-- The Grid item #1 --><article class=\"tg-item tg-post-80359 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2025\/05\/FLO_Drone_006FLO_Drone_006.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Die Lagune<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/die-lagune\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #2 --><article class=\"tg-item tg-post-83205 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/trotinette-2026-banner.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Elektroroller<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/elektroroller\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #3 --><article class=\"tg-item tg-post-83090 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2026\/04\/tir-a-l-arc-2026-banner.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Bogenschie\u00dfen<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/bogenschiessen\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #4 --><article class=\"tg-item tg-post-69814 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/01\/VFP_ACTIVITES_0039_le_futuroscope_30_ans_de_design_thinking_inspire_par_les_nouvelles_technologies.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Tourismus<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/tourismus\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #5 --><article class=\"tg-item tg-post-72092 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_activites_famille_017-1.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Angeln<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/angeln\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #6 --><article class=\"tg-item tg-post-72111 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/GettyImages-949446550.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Wandern<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/wandern\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #7 --><article class=\"tg-item tg-post-72101 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2018\/12\/activite-piscine.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Schwimmbad<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/schwimmbad\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><!-- The Grid item #8 --><article class=\"tg-item tg-post-72078 tg-activities-de f61\" data-row=\"1\" data-col=\"1\"><div class=\"tg-item-inner\"><div class=\"tg-item-media-holder tg-light\"><div class=\"tg-item-media-inner\"><div class=\"tg-item-image\" style=\"background-image: url(https:\/\/village-flottant-pressac.com\/wp-content\/uploads\/2021\/07\/2021_Village_flottant_pressac_bain_nordique_003-1.jpg)\"><\/div><\/div><div class=\"tg-item-media-content \"><div class=\"tg-item-overlay\"><\/div><div class=\"tg-top-holder\"><h2 class=\"tg-item-title tg-element-1\">Nordisches Bad<\/h2><\/div><div class=\"tg-center-holder\"><div class=\"tg-center-inner\"><div class=\"tg-element-2\"><a target=\"_self\" href=\"https:\/\/village-flottant-pressac.com\/de\/aktivitaeten\/nordisches-bad\/\">Mehr erfahren<\/a><\/div><div class=\"tg-item-clear\"><\/div><\/div><\/div><\/div><\/div><\/div><\/article><\/div><\/div><!-- The Grid Wrapper End -->angelnschwimmbadwandernnordisches badTourismus<\/p>\n","protected":false},"author":14,"featured_media":83095,"parent":69790,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-83090","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/pages\/83090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/comments?post=83090"}],"version-history":[{"count":4,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/pages\/83090\/revisions"}],"predecessor-version":[{"id":83321,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/pages\/83090\/revisions\/83321"}],"up":[{"embeddable":true,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/pages\/69790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/media\/83095"}],"wp:attachment":[{"href":"https:\/\/village-flottant-pressac.com\/de\/wp-json\/wp\/v2\/media?parent=83090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}